{"id":2931,"date":"2026-06-25T10:20:52","date_gmt":"2026-06-25T16:20:52","guid":{"rendered":"https:\/\/cisne.mx\/?post_type=podcast&amp;p=2931"},"modified":"2026-06-25T10:20:52","modified_gmt":"2026-06-25T16:20:52","slug":"millennial-brain-el-manual-que-no-te-dieron-con-fernando-soberon-ep-51","status":"publish","type":"podcast","link":"https:\/\/mentealcuadrado.com\/index.php\/podcast\/millennial-brain-el-manual-que-no-te-dieron-con-fernando-soberon-ep-51\/","title":{"rendered":"Millennial Brain: El manual que no te dieron con Fernando Sober\u00f3n Ep. 51"},"content":{"rendered":"<p>\u00bfHiciste todo lo que te dijeron para \u00abtriunfar\u00bb y a\u00fan as\u00ed sientes agotamiento, ansiedad y estancamiento? \ud83e\udde0\ud83d\udca5<br \/>\nEn este episodio, Fernando Sober\u00f3n nos ayuda a abrir la caja negra de la mente Millennial.<br \/>\nCrecimos con reglas que cambiaron a medio camino. Nos ense\u00f1aron a esforzarnos hasta el l\u00edmite, a callar la intuici\u00f3n y a vivir pendientes de un cr\u00edtico interno que nunca aplaude.<br \/>\nAqu\u00ed desmontamos esos mitos y compartimos claves reales para entrenar bonito a tu mente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfHiciste todo lo que te dijeron para \u00abtriunfar\u00bb y a\u00fan as\u00ed sientes agotamiento, ansiedad y estancamiento? \ud83e\udde0\ud83d\udca5<br \/>\nEn este episodio, Fernando Sober\u00f3n nos ayuda a abrir la caja negra de la mente Millennial.<br \/>\nCrecimos con reglas que cambiaron a medio camino. Nos ense\u00f1aron a esforzarnos hasta el l\u00edmite, a callar la intuici\u00f3n y a vivir pendientes de un cr\u00edtico interno que nunca aplaude.<br \/>\nAqu\u00ed desmontamos esos mitos y compartimos claves reales para entrenar bonito a tu mente.<\/p>\n","protected":false},"author":5,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","episode_type":"audio","audio_file":"https:\/\/mentealcuadrado.com\/wp-content\/uploads\/2026\/06\/M2-Pod-3-Fernando-Soberon-Master-1080p-24fps.mp3","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"https:\/\/mentealcuadrado.com\/wp-content\/uploads\/2026\/06\/FerSoberon-scaled.png","cover_image_id":"2970","duration":"00:29:17","filesize":"54.54M","filesize_raw":"57188397","date_recorded":"2026-06-25 08:22:13","explicit":"","block":"","itunes_episode_number":"51","itunes_title":"Millennial Brain: El manual que no te dieron con Fernando Sober\u00f3n","itunes_season_number":"","itunes_episode_type":"full"},"tags":[10,87,88,89,90,7],"series":[14],"class_list":["post-2931","podcast","type-podcast","status-publish","hentry","tag-cerebro","tag-creencias","tag-intuicion","tag-limites","tag-millennials","tag-salud-mental","series-mente-al-cuadrado"],"episode_featured_image":false,"episode_player_image":"https:\/\/mentealcuadrado.com\/wp-content\/uploads\/2026\/06\/FerSoberon-scaled.png","download_link":"https:\/\/mentealcuadrado.com\/podcast-download\/2931\/millennial-brain-el-manual-que-no-te-dieron-con-fernando-soberon-ep-51","player_link":"https:\/\/mentealcuadrado.com\/podcast-player\/2931\/millennial-brain-el-manual-que-no-te-dieron-con-fernando-soberon-ep-51","audio_player":"<a class=\"wp-embedded-audio\" href=\"https:\/\/mentealcuadrado.com\/podcast-player\/2931\/millennial-brain-el-manual-que-no-te-dieron-con-fernando-soberon-ep-51\">https:\/\/mentealcuadrado.com\/podcast-player\/2931\/millennial-brain-el-manual-que-no-te-dieron-con-fernando-soberon-ep-51<\/a>","episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/mentealcuadrado.com\/feed\/podcast\/mente-al-cuadrado","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"HAJXs20vYL\"><a href=\"https:\/\/mentealcuadrado.com\/index.php\/podcast\/millennial-brain-el-manual-que-no-te-dieron-con-fernando-soberon-ep-51\/\">Millennial Brain: El manual que no te dieron con Fernando Sober\u00f3n Ep. 51<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/mentealcuadrado.com\/index.php\/podcast\/millennial-brain-el-manual-que-no-te-dieron-con-fernando-soberon-ep-51\/embed\/#?secret=HAJXs20vYL\" width=\"500\" height=\"350\" title=\"\u00abMillennial Brain: El manual que no te dieron con Fernando Sober\u00f3n Ep. 51\u00bb \u2014 Mente al Cuadrado\" data-secret=\"HAJXs20vYL\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/mentealcuadrado.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/podcast\/2931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/podcast"}],"about":[{"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/types\/podcast"}],"author":[{"embeddable":true,"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/comments?post=2931"}],"wp:attachment":[{"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/media?parent=2931"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/tags?post=2931"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/series?post=2931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}