{"id":2870,"date":"2026-02-26T14:52:26","date_gmt":"2026-02-26T20:52:26","guid":{"rendered":"https:\/\/cisne.mx\/?post_type=podcast&amp;p=2870"},"modified":"2026-02-26T14:52:26","modified_gmt":"2026-02-26T20:52:26","slug":"el-fin-de-la-rigidez-muscular-y-el-dolor-cronico-un-traje-inteligente-con-rene-govea-ep-44","status":"publish","type":"podcast","link":"https:\/\/mentealcuadrado.com\/index.php\/podcast\/el-fin-de-la-rigidez-muscular-y-el-dolor-cronico-un-traje-inteligente-con-rene-govea-ep-44\/","title":{"rendered":"\u00bfEl fin de la rigidez muscular y el dolor cr\u00f3nico? | Un traje inteligente con Ren\u00e9 Govea Ep. 44"},"content":{"rendered":"<p>El futuro de la rehabilitaci\u00f3n lleg\u00f3 a M\u00e9xico. \ud83e\udde0\ud83e\uddbe<\/p>\n<p>\u00bfTe imaginas un traje que \u00abense\u00f1e\u00bb a tus m\u00fasculos a relajarse? En este episodio, recibimos al Lic. Ren\u00e9 Gobea Hern\u00e1ndez para platicar sobre el Exopulse Mollii Suit, una innovaci\u00f3n m\u00e9dica de neuromodulaci\u00f3n perif\u00e9rica que est\u00e1 revolucionando el tratamiento de la espasticidad y el dolor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El futuro de la rehabilitaci\u00f3n lleg\u00f3 a M\u00e9xico. \ud83e\udde0\ud83e\uddbe<br \/>\n\u00bfTe imaginas un traje que \u00abense\u00f1e\u00bb a tus m\u00fasculos a relajarse? En este episodio, recibimos al Lic. Ren\u00e9 Gobea Hern\u00e1ndez para platicar sobre el Exopulse Mollii Suit, una innovaci\u00f3n m\u00e9dica de neuromodulaci\u00f3n perif\u00e9rica que est\u00e1 revolucionando el tratamiento de la espasticidad y el dolor.<\/p>\n","protected":false},"author":5,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","episode_type":"audio","audio_file":"https:\/\/mentealcuadrado.com\/wp-content\/uploads\/2026\/02\/Episodio-M2-Rene-Govea.mp3","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"00:31:23","filesize":"28.74M","filesize_raw":"30131081","date_recorded":"2026-02-26","explicit":"","block":"","itunes_episode_number":"44","itunes_title":"\u00bfEl fin de la rigidez muscular y el dolor cr\u00f3nico? | Un traje inteligente con Ren\u00e9 Govea Ep. 44","itunes_season_number":"","itunes_episode_type":""},"tags":[],"series":[14],"class_list":["post-2870","podcast","type-podcast","status-publish","hentry","series-mente-al-cuadrado"],"episode_featured_image":false,"episode_player_image":"https:\/\/mentealcuadrado.com\/wp-content\/uploads\/2026\/08\/portada-podcast.jpg","download_link":"https:\/\/mentealcuadrado.com\/podcast-download\/2870\/el-fin-de-la-rigidez-muscular-y-el-dolor-cronico-un-traje-inteligente-con-rene-govea-ep-44","player_link":"https:\/\/mentealcuadrado.com\/podcast-player\/2870\/el-fin-de-la-rigidez-muscular-y-el-dolor-cronico-un-traje-inteligente-con-rene-govea-ep-44","audio_player":"<a class=\"wp-embedded-audio\" href=\"https:\/\/mentealcuadrado.com\/podcast-player\/2870\/el-fin-de-la-rigidez-muscular-y-el-dolor-cronico-un-traje-inteligente-con-rene-govea-ep-44\">https:\/\/mentealcuadrado.com\/podcast-player\/2870\/el-fin-de-la-rigidez-muscular-y-el-dolor-cronico-un-traje-inteligente-con-rene-govea-ep-44<\/a>","episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/mentealcuadrado.com\/feed\/podcast\/mente-al-cuadrado","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"BCSE3lwqhn\"><a href=\"https:\/\/mentealcuadrado.com\/index.php\/podcast\/el-fin-de-la-rigidez-muscular-y-el-dolor-cronico-un-traje-inteligente-con-rene-govea-ep-44\/\">\u00bfEl fin de la rigidez muscular y el dolor cr\u00f3nico? | Un traje inteligente con Ren\u00e9 Govea Ep. 44<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/mentealcuadrado.com\/index.php\/podcast\/el-fin-de-la-rigidez-muscular-y-el-dolor-cronico-un-traje-inteligente-con-rene-govea-ep-44\/embed\/#?secret=BCSE3lwqhn\" width=\"500\" height=\"350\" title=\"\u00ab\u00bfEl fin de la rigidez muscular y el dolor cr\u00f3nico? | Un traje inteligente con Ren\u00e9 Govea Ep. 44\u00bb \u2014 Mente al Cuadrado\" data-secret=\"BCSE3lwqhn\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/mentealcuadrado.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/podcast\/2870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/podcast"}],"about":[{"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/types\/podcast"}],"author":[{"embeddable":true,"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/comments?post=2870"}],"wp:attachment":[{"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/media?parent=2870"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/tags?post=2870"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/series?post=2870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}