{"id":2825,"date":"2025-12-04T12:06:50","date_gmt":"2025-12-04T18:06:50","guid":{"rendered":"https:\/\/cisne.mx\/?post_type=podcast&amp;p=2825"},"modified":"2025-12-04T12:06:50","modified_gmt":"2025-12-04T18:06:50","slug":"entre-moda-y-ciencia-que-si-funciona-con-la-dra-glady-sastre-episodio-40-de-mente-al-cuadrado","status":"publish","type":"podcast","link":"https:\/\/mentealcuadrado.com\/index.php\/podcast\/entre-moda-y-ciencia-que-si-funciona-con-la-dra-glady-sastre-episodio-40-de-mente-al-cuadrado\/","title":{"rendered":"Entre moda y ciencia: \u00bfqu\u00e9 s\u00ed funciona? con la Dra. Glady Sastr\u00e9 &#8211; Episodio 40 de Mente al Cuadrado"},"content":{"rendered":"<p>En este nuevo cap\u00edtulo de Mente al Cuadrado, nos adentramos en el mundo donde las tendencias de bienestar se mezclan con la evidencia cient\u00edfica. La Dra. Glady Sastr\u00e9, especialista en Medicina Funcional Integrativa y salud femenina, se une a la conversaci\u00f3n para responder una pregunta clave:<\/p>\n<p>\u00bfQu\u00e9 s\u00ed funciona\u2026 y qu\u00e9 es solo moda?<\/p>\n<p>Con la experiencia de la Dra. Sastr\u00e9 y el an\u00e1lisis del Dr. Edilberto Pe\u00f1a, desmenuzamos creencias, viralidades y verdades inc\u00f3modas para ayudarte a tomar decisiones m\u00e1s informadas sobre tu salud.<\/p>\n<p>Comparte este episodio con alguien que est\u00e9 buscando respuestas entre tanto ruido.<br \/>\nSuscr\u00edbete para m\u00e1s conversaciones que unen ciencia, salud y vida real.<\/p>\n<p>#SaludMental #ModayCiencia #Saludfemenina #Psicolog\u00eda #Psiquiatr\u00eda #MedicinaFuncional #MenteAlCuadrado #EdilbertoPe\u00f1a #SaludEmocional #Bienestar #PodcastM\u00e9xico #ConversacionesQueSanen<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En este nuevo cap\u00edtulo de Mente al Cuadrado, nos adentramos en el mundo donde las tendencias de bienestar se mezclan con la evidencia cient\u00edfica. La Dra. Glady Sastr\u00e9, especialista en Medicina Funcional Integrativa y salud femenina, se une a la conversaci\u00f3n para responder una pregunta clave: \u00bfQu\u00e9 s\u00ed funciona\u2026 y qu\u00e9 es solo moda? Con [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","episode_type":"audio","audio_file":"https:\/\/mentealcuadrado.com\/wp-content\/uploads\/2025\/12\/Episodio-M2-Gladys-Sastre.mp3","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"https:\/\/mentealcuadrado.com\/wp-content\/uploads\/2025\/12\/GladysSastre-M2-1080X1080.jpg","cover_image_id":"2978","duration":"29:38","filesize":"27.14M","filesize_raw":"28456841","date_recorded":"2025-12-04 12:06:50","explicit":"","block":"","itunes_episode_number":"11","itunes_title":"Entre moda y ciencia: \u00bfqu\u00e9 s\u00ed funciona? con la Dra. Glady Sastr\u00e9 - Episodio 40","itunes_season_number":"3","itunes_episode_type":"full"},"tags":[71],"series":[14],"class_list":["post-2825","podcast","type-podcast","status-publish","hentry","tag-medicinal-funcional","series-mente-al-cuadrado"],"episode_featured_image":false,"episode_player_image":"https:\/\/mentealcuadrado.com\/wp-content\/uploads\/2025\/12\/GladysSastre-M2-1080X1080.jpg","download_link":"https:\/\/mentealcuadrado.com\/podcast-download\/2825\/entre-moda-y-ciencia-que-si-funciona-con-la-dra-glady-sastre-episodio-40-de-mente-al-cuadrado","player_link":"https:\/\/mentealcuadrado.com\/podcast-player\/2825\/entre-moda-y-ciencia-que-si-funciona-con-la-dra-glady-sastre-episodio-40-de-mente-al-cuadrado","audio_player":"<a class=\"wp-embedded-audio\" href=\"https:\/\/mentealcuadrado.com\/podcast-player\/2825\/entre-moda-y-ciencia-que-si-funciona-con-la-dra-glady-sastre-episodio-40-de-mente-al-cuadrado\">https:\/\/mentealcuadrado.com\/podcast-player\/2825\/entre-moda-y-ciencia-que-si-funciona-con-la-dra-glady-sastre-episodio-40-de-mente-al-cuadrado<\/a>","episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/mentealcuadrado.com\/feed\/podcast\/mente-al-cuadrado","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"TtuLADlt0s\"><a href=\"https:\/\/mentealcuadrado.com\/index.php\/podcast\/entre-moda-y-ciencia-que-si-funciona-con-la-dra-glady-sastre-episodio-40-de-mente-al-cuadrado\/\">Entre moda y ciencia: \u00bfqu\u00e9 s\u00ed funciona? con la Dra. Glady Sastr\u00e9 &#8211; Episodio 40 de Mente al Cuadrado<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/mentealcuadrado.com\/index.php\/podcast\/entre-moda-y-ciencia-que-si-funciona-con-la-dra-glady-sastre-episodio-40-de-mente-al-cuadrado\/embed\/#?secret=TtuLADlt0s\" width=\"500\" height=\"350\" title=\"\u00abEntre moda y ciencia: \u00bfqu\u00e9 s\u00ed funciona? con la Dra. Glady Sastr\u00e9 &#8211; Episodio 40 de Mente al Cuadrado\u00bb \u2014 Mente al Cuadrado\" data-secret=\"TtuLADlt0s\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/mentealcuadrado.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/podcast\/2825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/podcast"}],"about":[{"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/types\/podcast"}],"author":[{"embeddable":true,"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/comments?post=2825"}],"wp:attachment":[{"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/media?parent=2825"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/tags?post=2825"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/series?post=2825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}