{"id":2355,"date":"2024-08-29T23:42:36","date_gmt":"2024-08-29T23:42:36","guid":{"rendered":"https:\/\/cisne.mx\/?post_type=podcast&amp;p=2355"},"modified":"2024-08-29T23:42:36","modified_gmt":"2024-08-29T23:42:36","slug":"la-menopausia-que-no-te-cuentan-con-la-dra-julie-salomon","status":"publish","type":"podcast","link":"https:\/\/mentealcuadrado.com\/index.php\/podcast\/la-menopausia-que-no-te-cuentan-con-la-dra-julie-salomon\/","title":{"rendered":"La menopausia que no te cuentan con la Dra. Julie Salom\u00f3n"},"content":{"rendered":"<p><span class=\"yt-core-attributed-string--link-inherit-color\" dir=\"auto\">En este episodio de Mente al Cuadrado, hablamos con la Dra. Julie Salom\u00f3n, ginec\u00f3loga, sobre \u00abLa menopausia que no te cuentan\u00bb. La Dra. Salom\u00f3n nos revela aspectos poco conocidos de la menopausia, m\u00e1s all\u00e1 de los s\u00edntomas comunes, y c\u00f3mo manejar esta etapa con conocimiento y tranquilidad. Si alguna vez te has preguntado qu\u00e9 m\u00e1s hay detr\u00e1s de este cambio tan importante en la vida de las mujeres, \u00a1no te pierdas esta valiosa conversaci\u00f3n!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En este episodio de Mente al Cuadrado, hablamos con la Dra. Julie Salom\u00f3n, ginec\u00f3loga, sobre \u00abLa menopausia que no te cuentan\u00bb. La Dra. Salom\u00f3n nos revela aspectos poco conocidos de la menopausia, m\u00e1s all\u00e1 de los s\u00edntomas comunes, y c\u00f3mo manejar esta etapa con conocimiento y tranquilidad. Si alguna vez te has preguntado qu\u00e9 m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","episode_type":"audio","audio_file":"https:\/\/mentealcuadrado.com\/wp-content\/uploads\/2024\/08\/MENTE-AL-CUADRADO-M2-JULIE.mp3","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"https:\/\/mentealcuadrado.com\/wp-content\/uploads\/2024\/08\/M2-1000x1000-Julie-Solomon-Ago.png","cover_image_id":"3004","duration":"24:32","filesize":"22.47M","filesize_raw":"23559242","date_recorded":"2024-08-29 23:42:36","explicit":"","block":"","itunes_episode_number":"4","itunes_title":"La menopausia que no te cuentan con la Dra. Julie Salom\u00f3n","itunes_season_number":"2","itunes_episode_type":"full"},"tags":[25,26,7],"series":[14],"class_list":["post-2355","podcast","type-podcast","status-publish","hentry","tag-menopausia","tag-mujeres","tag-salud-mental","series-mente-al-cuadrado"],"episode_featured_image":false,"episode_player_image":"https:\/\/mentealcuadrado.com\/wp-content\/uploads\/2024\/08\/M2-1000x1000-Julie-Solomon-Ago.png","download_link":"https:\/\/mentealcuadrado.com\/podcast-download\/2355\/la-menopausia-que-no-te-cuentan-con-la-dra-julie-salomon","player_link":"https:\/\/mentealcuadrado.com\/podcast-player\/2355\/la-menopausia-que-no-te-cuentan-con-la-dra-julie-salomon","audio_player":"<a class=\"wp-embedded-audio\" href=\"https:\/\/mentealcuadrado.com\/podcast-player\/2355\/la-menopausia-que-no-te-cuentan-con-la-dra-julie-salomon\">https:\/\/mentealcuadrado.com\/podcast-player\/2355\/la-menopausia-que-no-te-cuentan-con-la-dra-julie-salomon<\/a>","episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/mentealcuadrado.com\/feed\/podcast\/mente-al-cuadrado","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"ymdt6nITdM\"><a href=\"https:\/\/mentealcuadrado.com\/index.php\/podcast\/la-menopausia-que-no-te-cuentan-con-la-dra-julie-salomon\/\">La menopausia que no te cuentan con la Dra. Julie Salom\u00f3n<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/mentealcuadrado.com\/index.php\/podcast\/la-menopausia-que-no-te-cuentan-con-la-dra-julie-salomon\/embed\/#?secret=ymdt6nITdM\" width=\"500\" height=\"350\" title=\"\u00abLa menopausia que no te cuentan con la Dra. Julie Salom\u00f3n\u00bb \u2014 Mente al Cuadrado\" data-secret=\"ymdt6nITdM\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/mentealcuadrado.com\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/podcast\/2355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/podcast"}],"about":[{"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/types\/podcast"}],"author":[{"embeddable":true,"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/comments?post=2355"}],"wp:attachment":[{"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/media?parent=2355"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/tags?post=2355"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/mentealcuadrado.com\/index.php\/wp-json\/wp\/v2\/series?post=2355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}